{"id":636,"date":"2021-12-28T12:51:54","date_gmt":"2021-12-28T11:51:54","guid":{"rendered":"https:\/\/www.rome.info\/it\/?page_id=636"},"modified":"2021-12-28T12:51:54","modified_gmt":"2021-12-28T11:51:54","slug":"trastevere","status":"publish","type":"page","link":"https:\/\/www.rome.info\/it\/trastevere\/","title":{"rendered":"Trastevere, Roma"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full\"><img decoding=\"async\" width=\"177\" height=\"133\" src=\"https:\/\/www.rome.info\/it\/wp-content\/uploads\/sites\/4\/trastevere2.jpg\" alt=\"\" class=\"wp-image-637\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La storia d\u2019 amore fra il quartiere Trastevere ed i romani e forestieri ha radici profonde e lontane nel tempo. La denominazione Trastevere deriva dal latino Trans Tiber e significa \u201c al di la del Tevere\u201d: questo perch\u00e9 geograficamente l \u2018area sorge sulla riva destra del fiume Tevere ( laddove gli altri rioni della citta, al tempo dell\u2019 antica Roma, erano locati sulla riva sinistra), il che ha permesso al quartiere di diventare( a cominciare dall\u2019 epoca romana) il principale porto fluviale della citta( il Porto di Ripa Grande) collegandolo ad\u00a0<a href=\"https:\/\/www.rome.info\/it\/ostia\/\">Ostia<\/a>\u00a0ed al mare. Gia nel passato( dall\u2019 epoca dell\u2019 Imperatore Augusto), Trastevere ha ospitato gente proveniente da ogni dove: commercianti ebrei, che hanno avuto un ruolo centrale nel Medioevo( poi trasferitisi, nel 15\u00b0 secolo, sulla riva opposta del fiume, nel Ghetto Ebraico), avventori provenienti da ogni parte della penisola e stranieri provenienti dai territori al di la delle Alpi. Quartiere accogliente, dunque, aperto alle influenze esterne ma anche profondamente romano. Con il passare dei secoli, il fascino di Trastevere non e poi cosi cambiato( al di la degli ovvi cambiamenti del tessuto urbano ed anche dei mutamenti sociali, che hanno portato a sostituire via via alle botteghe artigiane tutta una serie di\u00a0<a href=\"https:\/\/www.rome.info\/it\/ristoranti\/\">ristoranti<\/a>\u00a0per turisti, birrerie, take away etnici, negozi alternativi, librerie, sale da te o internet cafe ).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-full\"><img decoding=\"async\" width=\"100\" height=\"133\" src=\"https:\/\/www.rome.info\/it\/wp-content\/uploads\/sites\/4\/trastevere.jpg\" alt=\"\" class=\"wp-image-638\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Oggi, accanto a romani che abitano il rione da diverse generazioni( ormai molto pochi, a dire il vero) ed ai nuovi ricchi che abitano i grandi e costosi appartamenti ristrutturati( giornalisti, intellettuali un poco snob, figli di papa dal portafoglio gonfio, professori universitari), e tutto un pullulare di stranieri( pittori, espatriati facoltosi, studenti della John Cabot e dell\u2019 American Academy, due universita americane della citta ), attirati dal fascino di questi vicoli cosi carichi di storia e di carattere e dai tesori che Trastevere svela, alcuni sotto gli occhi di tutti(&nbsp;<strong>la Chiesa di Santa Maria in Trastevere<\/strong>, quella di Santa Cecilia od di Santa Maria della Scala, San Pietro al Montorio ed il Tempietto del Bramante, l\u2019 Isola Tiberina, il Gianicolo, da cui si gode una veduta di Roma da togliere il fiato o l\u2019 Orto Botanico), altri piu nascosti, altri legati ai piaceri della gola e dei sensi( il mercato di piazza San Cosimato, il caotico mercato delle pulci di&nbsp;<strong>Porta Portese<\/strong>, la pasticceria di Vicolo del Cinque o la festa folkoristica De\u2019 Noantri a meta agosto).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La notte, poi, il quartiere cambia volto, lasciando spazio ai divertimenti della&nbsp;<a href=\"https:\/\/www.rome.info\/it\/intrattenimento\/vita-notturna\/\">vita notturna<\/a>( di qualsiasi tipo vogliate: una passeggiata, una birra in uno dei tanti&nbsp;<a href=\"https:\/\/www.rome.info\/clubs\/\">locali notturni<\/a>, uno spuntino di mezzanotte). Agli abitanti del quartiere( meno accoglienti di un tempo, a dire il vero, infastiditi dai venditori di strada o dal traffico e dalla folla rumorosa, qualche volta un po\u2019 alticcia, che affolla i tavoli all\u2019aperto o passeggia per i vicoli,) si sostituiscono frotte di personaggi attirati dalle opportunita e dal fascino del rione. Il fascino di Trastevere, comunque, rimane immutato nel tempo. Che sia di giorno o di notte, passeggiare per il suo labirinto di strade rimane un\u2019 esperienza da raccontare.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Raggiungere Trastevere<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Treni<\/strong>( treno-denominato regionale, non il treno espresso da Termini) partono dall\u2018 aereoporto L da vinci ed arrivano alla stazione ferroviaria di Trastevere. Da qui, si prende il tram numero 8<br><strong>Tram<\/strong>&nbsp;n\u00b0 8 Da largo argentina. E\u2018 disponibile un comodo tram che da Trastevere conduce fino al Pantheon e che passa frequentemente.<br><strong>Autobus notturno<\/strong>&nbsp;numero 8<br><strong>Autobus H<\/strong>&nbsp;dalla Stazione Termini( la principale stazione ferroviaria)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>NB:<\/strong>&nbsp;Le autovetture dei non residenti non possono parcheggiare a Trastevere durante le ore serali per cui e consigliabile parcheggiare nelle prossimita del quartiere e raggiungerlo a piedi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","button_url":"","ms_product_id":"","ms_product_name":"","ms_price":"","ms_currency":"","ms_rating_value":"","ms_review_count":"","rank_math_title":"Trastevere Roma %sep% %sitename%","rank_math_description":""},"post-style":[],"producer":[],"class_list":["post-636","page","type-page","status-publish","has-post-thumbnail"],"acf":[],"product_schema":{"ms_product_id":"","ms_product_name":"","ms_price":"","ms_currency":"","ms_rating_value":"","ms_review_count":""},"_links":{"self":[{"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/pages\/636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/comments?post=636"}],"version-history":[{"count":0,"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/pages\/636\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/media?parent=636"}],"wp:term":[{"taxonomy":"post-style","embeddable":true,"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/post-style?post=636"},{"taxonomy":"producer","embeddable":true,"href":"https:\/\/www.rome.info\/it\/wp-json\/wp\/v2\/producer?post=636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}